{"id":210369,"date":"2012-02-24T00:00:00","date_gmt":"2012-02-24T00:00:00","guid":{"rendered":"https:\/\/www.ecuadortimes.net\/es\/gutemberg-vera-trato-de-sobornarme-dice-ex-jueza-encalada\/"},"modified":"2012-02-24T00:00:00","modified_gmt":"2012-02-24T00:00:00","slug":"gutemberg-vera-trato-de-sobornarme-dice-ex-jueza-encalada","status":"publish","type":"post","link":"https:\/\/www.ecuadortimes.net\/es\/gutemberg-vera-trato-de-sobornarme-dice-ex-jueza-encalada\/","title":{"rendered":"&#8220;Gutemberg Vera trat\u00f3 de sobornarme&#8221; dice ex jueza Encalada"},"content":{"rendered":"<div id=\"attachment_60144\" style=\"width: 280px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.ecuadortimes.net\/es\/2012\/02\/24\/gutemberg-vera-trato-de-sobornarme-dice-ex-jueza-encalada\/gutemberg-vera-5\/\" rel=\"attachment wp-att-60144\"><img aria-describedby=\"caption-attachment-60144\" loading=\"lazy\" class=\"size-medium wp-image-60144 \" title=\"Gutemberg Vera\" src=\"http:\/\/media.ecuadortimes.net\/2012\/02\/Gutemberg-Vera1-300x212.jpg\" alt=\"Gutemberg Vera\" width=\"270\" height=\"191\" \/><\/a><p id=\"caption-attachment-60144\" class=\"wp-caption-text\">Gutemberg Vera<\/p><\/div>\n<p>Desde\u00a0<strong>Bogot\u00e1<\/strong>\u00a0,\u00a0<strong>Colombia<\/strong>, la ex jueza\u00a0<strong>M\u00f3nica<\/strong>\u00a0<strong>Encalada<\/strong>\u00a0hizo serias declaraciones sobre el caso\u00a0<strong>El<\/strong>\u00a0<strong>Universo<\/strong>. Durante una entrevista con\u00a0<strong>Teleamazonas<\/strong>, la ex funcionaria judicial revel\u00f3 que Gutemberg Vera, abogado defensor del presidente de la Rep\u00fablica,\u00a0<strong>Rafael<\/strong>\u00a0<strong>Correa<\/strong>, le ofreci\u00f3 $3.000<\/p>\n<p>Ecanlada tiene pruebas de que Vera trato de sobornarla dici\u00e9ndole, <em>Mi reina le voy a entregar 3.000 d\u00f3lares mensuales<\/em>\u009d. Ella tambi\u00e9n a\u00f1adi\u00f3 que su \u0098pen drive\u0099 no fue usado para hacer la sentencia como dijo el juez\u00a0<a href=\"http:\/\/www.ecuadortimes.net\/es\/2012\/02\/23\/juez-paredes-niega-acusaciones-de-monica-encalada\/\"><strong>Juan<\/strong><strong>Paredes<\/strong><\/a>. Al principio se cre\u00eda que el juez Paredes escribi\u00f3 la sentencia, sin embargo la verdadera cara detr\u00e1s de \u0098<strong>Chucky<\/strong>\u00a0<strong>Seven\u0099<\/strong>\u00a0es Gutemberg Vera.<\/p>\n<p>La ex jueza asegur\u00f3 que Paredes miente y que tiene pruebas de que \u00e9l la busc\u00f3 a ella. Las evidencias est\u00e1n a bien recaudo para seguridad de su familia. El d\u00eda de ayer la ex jueza dio una rueda de prensa en Bogot\u00e1 acompa\u00f1ada por\u00a0<strong>Lucy<\/strong>\u00a0<strong>Paredes<\/strong>\u00a0y\u00a0<strong>Francisco<\/strong>\u00a0<strong>Zambrano<\/strong>, del Comit\u00e9 Ecuatoriano de los DD.HH. y Sindicales. All\u00ed ratific\u00f3 su acusaci\u00f3n contra Gutemberg Vera. (AV)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde\u00a0Bogot\u00e1\u00a0,\u00a0Colombia, la ex jueza\u00a0M\u00f3nica\u00a0Encalada\u00a0hizo serias declaraciones sobre el caso\u00a0El\u00a0Universo. Durante una entrevista con\u00a0Teleamazonas, la ex funcionaria judicial revel\u00f3 que Gutemberg Vera, abogado defensor del presidente de la Rep\u00fablica,\u00a0Rafael\u00a0Correa, le ofreci\u00f3 $3.000 Ecanlada tiene pruebas de que Vera trato de sobornarla dici\u00e9ndole, Mi reina le voy a entregar 3.000 d\u00f3lares mensuales\u009d. Ella tambi\u00e9n a\u00f1adi\u00f3 que su \u0098pen drive\u0099 no fue usado para hacer la sentencia como dijo el juez\u00a0JuanParedes. Al principio se cre\u00eda que el juez Paredes escribi\u00f3 la sentencia, sin embargo la verdadera cara detr\u00e1s de \u0098Chucky\u00a0Seven\u0099\u00a0es Gutemberg Vera. La ex jueza asegur\u00f3 que Paredes miente y que tiene pruebas de que \u00e9l la busc\u00f3 a ella. Las evidencias est\u00e1n a bien recaudo para seguridad de su familia. El d\u00eda de ayer la ex jueza dio una rueda de prensa en Bogot\u00e1 acompa\u00f1ada por\u00a0Lucy\u00a0Paredes\u00a0y\u00a0Francisco\u00a0Zambrano, del Comit\u00e9 Ecuatoriano de los DD.HH. y Sindicales. All\u00ed ratific\u00f3 su acusaci\u00f3n contra Gutemberg Vera. (AV)<\/p>\n","protected":false},"author":1,"featured_media":210370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[40,37],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/210369"}],"collection":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/comments?post=210369"}],"version-history":[{"count":0,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/210369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media\/210370"}],"wp:attachment":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media?parent=210369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/categories?post=210369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/tags?post=210369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}