{"id":210463,"date":"2012-03-01T00:00:00","date_gmt":"2012-03-01T00:00:00","guid":{"rendered":"https:\/\/www.ecuadortimes.net\/es\/diario-el-universo-continuara-con-demanda-en-la-cidh\/"},"modified":"2012-03-01T00:00:00","modified_gmt":"2012-03-01T00:00:00","slug":"diario-el-universo-continuara-con-demanda-en-la-cidh","status":"publish","type":"post","link":"https:\/\/www.ecuadortimes.net\/es\/diario-el-universo-continuara-con-demanda-en-la-cidh\/","title":{"rendered":"Diario El Universo continuar\u00e1 con demanda en la CIDH"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/media.ecuadortimes.net\/2012\/03\/El-Universo-Newspaper3.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-60844\" title=\"Diario El Universo \" src=\"http:\/\/media.ecuadortimes.net\/2012\/03\/El-Universo-Newspaper3-300x167.jpg\" alt=\"\" width=\"300\" height=\"167\" \/><\/a>Diario El Universo<\/strong> public\u00f3 hoy un comunicado en el cual anuncia que continuar\u00e1 con la demanda internacional ante la <strong>Comisi\u00f3n Interamericana de Derechos Humanos<\/strong> (CIDH), para buscar que se borre el delito en contra de los hermanos P\u00e9rez, directivos del medio, y de Emilio Palacio, ex editor de opini\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan el comunicado p\u00fablico, &#8220;(&#8230;) continuaremos las acciones que ya hemos iniciado ante el sistema interamericano de protecci\u00f3n de los Derechos Humanos, para que se anule la sentencia que crea el precedente y dar un paso m\u00e1s en la b\u00fasqueda de garant\u00edas para el ejercicio de la libre expresi\u00f3n en Ecuador&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;Si bien la decisi\u00f3n del <strong>presidente Rafael Correa<\/strong> tuvo como consecuencia eliminar las sanciones personales y pecuniarias contenidas en la resoluci\u00f3n de la Corte Nacional, no es menos cierto que dicha resoluci\u00f3n, adem\u00e1s de haber causado da\u00f1os, deja un precedente legal que es una amenaza para el ejercicio de la libertad de expresi\u00f3n, derecho ciudadano fundamental&#8221;, se\u00f1al\u00f3 el comunicado. (FL)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diario El Universo public\u00f3 hoy un comunicado en el cual anuncia que continuar\u00e1 con la demanda internacional ante la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH), para buscar que se borre el delito en contra de los hermanos P\u00e9rez, directivos del medio, y de Emilio Palacio, ex editor de opini\u00f3n. Seg\u00fan el comunicado p\u00fablico, &#8220;(&#8230;) continuaremos las acciones que ya hemos iniciado ante el sistema interamericano de protecci\u00f3n de los Derechos Humanos, para que se anule la sentencia que crea el precedente y dar un paso m\u00e1s en la b\u00fasqueda de garant\u00edas para el ejercicio de la libre expresi\u00f3n en Ecuador&#8221;. &#8220;Si bien la decisi\u00f3n del presidente Rafael Correa tuvo como consecuencia eliminar las sanciones personales y pecuniarias contenidas en la resoluci\u00f3n de la Corte Nacional, no es menos cierto que dicha resoluci\u00f3n, adem\u00e1s de haber causado da\u00f1os, deja un precedente legal que es una amenaza para el ejercicio de la libertad de expresi\u00f3n, derecho ciudadano fundamental&#8221;, se\u00f1al\u00f3 el comunicado. (FL)<\/p>\n","protected":false},"author":1,"featured_media":210464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[40,37],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/210463"}],"collection":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/comments?post=210463"}],"version-history":[{"count":0,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/210463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media\/210464"}],"wp:attachment":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media?parent=210463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/categories?post=210463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/tags?post=210463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}