{"id":210492,"date":"2012-03-04T00:00:00","date_gmt":"2012-03-04T00:00:00","guid":{"rendered":"https:\/\/www.ecuadortimes.net\/es\/madre-de-justin-bieber-publicara-libro-de-su-vida\/"},"modified":"2012-03-04T00:00:00","modified_gmt":"2012-03-04T00:00:00","slug":"madre-de-justin-bieber-publicara-libro-de-su-vida","status":"publish","type":"post","link":"https:\/\/www.ecuadortimes.net\/es\/madre-de-justin-bieber-publicara-libro-de-su-vida\/","title":{"rendered":"Madre de Justin Bieber publicar\u00e1 libro de su vida"},"content":{"rendered":"<div id=\"attachment_61035\" style=\"width: 210px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.ecuadortimes.net\/es\/2012\/03\/04\/madre-de-justin-bieber-publicara-libro-de-su-vida\/madre_de_justin-2\/\" rel=\"attachment wp-att-61035\"><img aria-describedby=\"caption-attachment-61035\" loading=\"lazy\" class=\"size-medium wp-image-61035\" title=\"Madre de Justin Bieber publicar\u00e1 libro de su vida\" src=\"http:\/\/media.ecuadortimes.net\/2012\/03\/madre_de_justin1-200x300.jpg\" alt=\"Madre de Justin Bieber publicar\u00e1 libro de su vida\" width=\"200\" height=\"300\" \/><\/a><p id=\"caption-attachment-61035\" class=\"wp-caption-text\">Madre de Justin Bieber publicar\u00e1 libro de su vida<\/p><\/div>\n<p style=\"text-align: justify;\"><strong>Pattie Mallette<\/strong>, madre del ic\u00f3nico cantante adolecente <strong>Justin Bieber<\/strong> se prepara para el lanzamiento de su libro en el que cuenta su historia de madre adolecente y soltera.<\/p>\n<p style=\"text-align: justify;\">En <em>Nowhere but Up: The Story of Justin Bieber&#8217;s Mom<\/em>\u009d, Pattie narra la parte m\u00e1s oscura de su vida detallando su traum\u00e1ticas y dolorosas experiencias como madre soltera a temprana edad, a parte de su adicci\u00f3n a las drogas, su posterior rehabilitaci\u00f3n, y sus experiencias suicidas producto de una gran depresi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">El libro, escrito con ayuda del escritor A. J. Gregory, sar\u00e1 publicado en el mes de septiembre en <strong>Estados Unidos,<\/strong> seg\u00fan inform\u00f3 <strong>Hollywood Life<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Algunos cr\u00edticos ya han disparado contra Mallette, alegando que se quiere aprovechar de la fama de su hijo para sacar partida econ\u00f3mica, ya que un documento sobre su vida no es importante para un gran p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">(BG)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pattie Mallette, madre del ic\u00f3nico cantante adolecente Justin Bieber se prepara para el lanzamiento de su libro en el que cuenta su historia de madre adolecente y soltera. En Nowhere but Up: The Story of Justin Bieber&#8217;s Mom\u009d, Pattie narra la parte m\u00e1s oscura de su vida detallando su traum\u00e1ticas y dolorosas experiencias como madre soltera a temprana edad, a parte de su adicci\u00f3n a las drogas, su posterior rehabilitaci\u00f3n, y sus experiencias suicidas producto de una gran depresi\u00f3n. El libro, escrito con ayuda del escritor A. J. Gregory, sar\u00e1 publicado en el mes de septiembre en Estados Unidos, seg\u00fan inform\u00f3 Hollywood Life. Algunos cr\u00edticos ya han disparado contra Mallette, alegando que se quiere aprovechar de la fama de su hijo para sacar partida econ\u00f3mica, ya que un documento sobre su vida no es importante para un gran p\u00fablico. (BG)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44,37],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/210492"}],"collection":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/comments?post=210492"}],"version-history":[{"count":0,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/210492\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media?parent=210492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/categories?post=210492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/tags?post=210492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}