{"id":242760,"date":"2017-03-22T00:00:00","date_gmt":"2017-03-22T00:00:00","guid":{"rendered":"https:\/\/www.ecuadortimes.net\/es\/jovenes-emprendedores-a-los-60\/"},"modified":"2017-03-22T00:00:00","modified_gmt":"2017-03-22T00:00:00","slug":"jovenes-emprendedores-a-los-60","status":"publish","type":"post","link":"https:\/\/www.ecuadortimes.net\/es\/jovenes-emprendedores-a-los-60\/","title":{"rendered":"J\u00f3venes emprendedores a los 60"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"aligncenter wp-image-184467 size-full\" src=\"https:\/\/www.ecuadortimes.net\/es\/wp-content\/uploads\/2017\/03\/EMPRENDEDORES-ECUADORTIMES.jpg\" width=\"762\" height=\"428\" \/><\/p>\n<p>El menor del grupo tiene 56 a\u00f1os de edad y el mayor 76, juntos suman m\u00e1s de 1.500 a\u00f1os. Son 30 personas jubiladas que ingresaron a la universidad Santa Mar\u00eda (USM), en el programa de estudios para mayores.<\/p>\n<p>Los fines de semana, mientras sus nietos aprend\u00edan a leer, ellos hac\u00edan tareas de contabilidad, derecho y legislaci\u00f3n ecuatoriana, turismo, activaci\u00f3n de la inteligencia, PNL (programa neuroling\u00fc\u00edstica, es una estrategia de comunicaci\u00f3n, desarrollo personal y psicoterapia) y Coaching. Durante dos a\u00f1os asistieron a clases desde las 08:00 hasta las 13:00.<\/p>\n<p>Diario Expreso ayer asisti\u00f3 con ellos a una de las \u00faltimas clases. La energ\u00eda y \u00e1nimo que mostr\u00f3 el grupo habl\u00f3 por s\u00ed de por qu\u00e9 se animaron a ir a la universidad despu\u00e9s de la jubilaci\u00f3n. Para muchos fue un anhelo que se posterg\u00f3 para cumplir con la responsabilidad de ser padres y esposos y para otros es su segunda carrera.(I)<\/p>\n<p>Fuente: <a href=\"http:\/\/expreso.ec\/economia\/ecuador-economia-emprendimiento-adultosmayores-jubilados-GH1180989\">http:\/\/expreso.ec\/economia\/ecuador-economia-emprendimiento-adultosmayores-jubilados-GH1180989<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El menor del grupo tiene 56 a\u00f1os de edad y el mayor 76, juntos suman m\u00e1s de 1.500 a\u00f1os. Son 30 personas jubiladas que ingresaron a la universidad Santa Mar\u00eda (USM), en el programa de estudios para mayores. Los fines de semana, mientras sus nietos aprend\u00edan a leer, ellos hac\u00edan tareas de contabilidad, derecho y legislaci\u00f3n ecuatoriana, turismo, activaci\u00f3n de la inteligencia, PNL (programa neuroling\u00fc\u00edstica, es una estrategia de comunicaci\u00f3n, desarrollo personal y psicoterapia) y Coaching. Durante dos a\u00f1os asistieron a clases desde las 08:00 hasta las 13:00. Diario Expreso ayer asisti\u00f3 con ellos a una de las \u00faltimas clases. La energ\u00eda y \u00e1nimo que mostr\u00f3 el grupo habl\u00f3 por s\u00ed de por qu\u00e9 se animaron a ir a la universidad despu\u00e9s de la jubilaci\u00f3n. Para muchos fue un anhelo que se posterg\u00f3 para cumplir con la responsabilidad de ser padres y esposos y para otros es su segunda carrera.(I) Fuente: http:\/\/expreso.ec\/economia\/ecuador-economia-emprendimiento-adultosmayores-jubilados-GH1180989<\/p>\n","protected":false},"author":1,"featured_media":242761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[35],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/242760"}],"collection":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/comments?post=242760"}],"version-history":[{"count":0,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/242760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media\/242761"}],"wp:attachment":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media?parent=242760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/categories?post=242760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/tags?post=242760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}