{"id":242942,"date":"2017-04-10T00:00:00","date_gmt":"2017-04-10T00:00:00","guid":{"rendered":"https:\/\/www.ecuadortimes.net\/es\/a%c2%81ngel-polibio-cordova-cada-vez-que-me-muevo-esta-por-detras-la-policia\/"},"modified":"2017-04-10T00:00:00","modified_gmt":"2017-04-10T00:00:00","slug":"a%c2%81ngel-polibio-cordova-cada-vez-que-me-muevo-esta-por-detras-la-policia","status":"publish","type":"post","link":"https:\/\/www.ecuadortimes.net\/es\/a%c2%81ngel-polibio-cordova-cada-vez-que-me-muevo-esta-por-detras-la-policia\/","title":{"rendered":"\u00c3\u0081ngel Polibio C\u00f3rdova: Cada vez que me muevo est\u00e1 por detr\u00e1s la Polic\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"aligncenter wp-image-184846 size-full\" src=\"https:\/\/www.ecuadortimes.net\/es\/wp-content\/uploads\/2017\/04\/CEDATOS_ECUADORTIMES-1.jpg\" width=\"674\" height=\"450\" \/><\/p>\n<p>\u00c3\u0081ngel Polibio C\u00f3rdova, directivo de<strong> Cedatos<\/strong>, asegura que ha recibido amenazas y que est\u00e1 siendo acosado y perseguido por polic\u00edas.<\/p>\n<p>Cedatos presentar\u00e1 una demanda lo antes posible,  porque realmente estamos haciendo objetos de acoso\u009d. Expres\u00f3 Cordova.<\/p>\n<p>Sobre la actitud del presidente <strong>Rafael Correa<\/strong>, tomar\u00e1n una actitud mucho m\u00e1s cautelosa, fundamentada en principios, fundamentada en la ley,\u009d tenemos que defender nuestro honor, tenemos que defender la integridad de nuestra organizaci\u00f3n tengo que defender la integridad de la familia, porque si me trata a m\u00ed de criminal, mafioso, est\u00e1 tratando tambi\u00e9n a mis hijos, est\u00e1 tratando as\u00ed tambi\u00e9n a mi familia&#8230;\u009d (I)<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: <a href=\"http:\/\/www.eluniverso.com\/noticias\/2017\/04\/10\/nota\/6132118\/cada-vez-que-me-muevo-esta-detras-policia\">http:\/\/www.eluniverso.com\/noticias\/2017\/04\/10\/nota\/6132118\/cada-vez-que-me-muevo-esta-detras-policia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c3\u0081ngel Polibio C\u00f3rdova, directivo de Cedatos, asegura que ha recibido amenazas y que est\u00e1 siendo acosado y perseguido por polic\u00edas. Cedatos presentar\u00e1 una demanda lo antes posible, porque realmente estamos haciendo objetos de acoso\u009d. Expres\u00f3 Cordova. Sobre la actitud del presidente Rafael Correa, tomar\u00e1n una actitud mucho m\u00e1s cautelosa, fundamentada en principios, fundamentada en la ley,\u009d tenemos que defender nuestro honor, tenemos que defender la integridad de nuestra organizaci\u00f3n tengo que defender la integridad de la familia, porque si me trata a m\u00ed de criminal, mafioso, est\u00e1 tratando tambi\u00e9n a mis hijos, est\u00e1 tratando as\u00ed tambi\u00e9n a mi familia&#8230;\u009d (I) &nbsp; Fuente: http:\/\/www.eluniverso.com\/noticias\/2017\/04\/10\/nota\/6132118\/cada-vez-que-me-muevo-esta-detras-policia<\/p>\n","protected":false},"author":1,"featured_media":242943,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[54,40],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/242942"}],"collection":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/comments?post=242942"}],"version-history":[{"count":0,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/242942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media\/242943"}],"wp:attachment":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media?parent=242942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/categories?post=242942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/tags?post=242942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}