{"id":242950,"date":"2017-04-11T00:00:00","date_gmt":"2017-04-11T00:00:00","guid":{"rendered":"https:\/\/www.ecuadortimes.net\/es\/inicia-demanda-en-contra-de-siete-medios-de-comunicacion\/"},"modified":"2017-04-11T00:00:00","modified_gmt":"2017-04-11T00:00:00","slug":"inicia-demanda-en-contra-de-siete-medios-de-comunicacion","status":"publish","type":"post","link":"https:\/\/www.ecuadortimes.net\/es\/inicia-demanda-en-contra-de-siete-medios-de-comunicacion\/","title":{"rendered":"Inicia demanda en contra de siete medios de comunicaci\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-184869 alignright\" src=\"https:\/\/www.ecuadortimes.net\/es\/wp-content\/uploads\/2017\/04\/supercom1_ECUADORRTIMES-300x194.jpg\" alt=\"\" width=\"300\" height=\"194\" \/><\/p>\n<p>Siete medios de comunicaci\u00f3n enfrenta una demanda por no replicar una publicaci\u00f3n del diario argentino P\u00e1gina 12 sobre un supuesto \u0098enriquecimiento\u0099 del candidato a la Presidencia por CREO, Guillermo Lasso, a trav\u00e9s de 49 empresas offshore\u009d se tramita desde el martes 11 hasta el jueves 13 de abril del 2017 en la Superintendencia de Comunicaci\u00f3n (Supercom).<\/p>\n<p>La denuncia se present\u00f3 el 27 de marzo por el denominado Observatorio ciudadano por una comunicaci\u00f3n con calidad, y seg\u00fan el reglamento de tratamiento de denuncias, la Supercom ten\u00eda 90 d\u00edas para calificar y admitir el expediente, pero luego de diez d\u00edas ya convoc\u00f3 a audiencias.<\/p>\n<p>Este grupo acusa de incurrir en una supuesta censura previa\u009d, sancionada en la Ley con una multa de 10 salarios b\u00e1sicos unificados.<\/p>\n<p>A las audiencias deber\u00e1n ir El Comercio, La Hora, Televicentro, El Universo, Ecuavisa, Teleamazonas y Expreso.(I)<\/p>\n<p>Fuente: <a href=\"http:\/\/www.eluniverso.com\/noticias\/2017\/04\/11\/nota\/6133549\/tramite-queja-contra-medios\">http:\/\/www.eluniverso.com\/noticias\/2017\/04\/11\/nota\/6133549\/tramite-queja-contra-medios<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Siete medios de comunicaci\u00f3n enfrenta una demanda por no replicar una publicaci\u00f3n del diario argentino P\u00e1gina 12 sobre un supuesto \u0098enriquecimiento\u0099 del candidato a la Presidencia por CREO, Guillermo Lasso, a trav\u00e9s de 49 empresas offshore\u009d se tramita desde el martes 11 hasta el jueves 13 de abril del 2017 en la Superintendencia de Comunicaci\u00f3n (Supercom). La denuncia se present\u00f3 el 27 de marzo por el denominado Observatorio ciudadano por una comunicaci\u00f3n con calidad, y seg\u00fan el reglamento de tratamiento de denuncias, la Supercom ten\u00eda 90 d\u00edas para calificar y admitir el expediente, pero luego de diez d\u00edas ya convoc\u00f3 a audiencias. Este grupo acusa de incurrir en una supuesta censura previa\u009d, sancionada en la Ley con una multa de 10 salarios b\u00e1sicos unificados. A las audiencias deber\u00e1n ir El Comercio, La Hora, Televicentro, El Universo, Ecuavisa, Teleamazonas y Expreso.(I) Fuente: http:\/\/www.eluniverso.com\/noticias\/2017\/04\/11\/nota\/6133549\/tramite-queja-contra-medios<\/p>\n","protected":false},"author":1,"featured_media":242951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[40],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/242950"}],"collection":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/comments?post=242950"}],"version-history":[{"count":0,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/242950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media\/242951"}],"wp:attachment":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media?parent=242950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/categories?post=242950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/tags?post=242950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}