{"id":252137,"date":"2018-11-28T00:00:00","date_gmt":"2018-11-28T00:00:00","guid":{"rendered":"https:\/\/www.ecuadortimes.net\/es\/vicuna-reconoce-los-aportes-pero-dice-que-fueron-voluntarios-y-dice-que-su-acusador-quiso-extorsionarla\/"},"modified":"2018-11-28T00:00:00","modified_gmt":"2018-11-28T00:00:00","slug":"vicuna-reconoce-los-aportes-pero-dice-que-fueron-voluntarios-y-dice-que-su-acusador-quiso-extorsionarla","status":"publish","type":"post","link":"https:\/\/www.ecuadortimes.net\/es\/vicuna-reconoce-los-aportes-pero-dice-que-fueron-voluntarios-y-dice-que-su-acusador-quiso-extorsionarla\/","title":{"rendered":"Vicu\u00f1a reconoce los aportes pero dice que fueron voluntarios y dice que su acusador quiso extorsionarla"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img src=\"https:\/\/www.ecuadortimes.net\/es\/wp-content\/uploads\/2018\/11\/Los-frentes-en-contra-de-la-vicepresidenta-se-multiplican_ecuadortimes_ecuadornews_4.jpg\" alt=\"\" class=\"wp-image-201156\"\/><\/figure><\/div>\n\n\n\n<p>La vicepresidenta de la Rep\u00fablica de Ecuador,&nbsp;<a href=\"https:\/\/www.larepublica.ec\/blog\/politica\/2018\/11\/27\/vicuna-se-defiende-sobre-los-supuestos-diezmos-infamias-y-calumnias\/\"><strong>Mar\u00eda Alejandra Vicu\u00f1a<\/strong><\/a>, realiz\u00f3 una rueda de prensa (en la que no acept\u00f3 cuestionamientos) para defenderse de las acusaciones de un exasesor que la involucra en supuestos cobros indebidos cuando la funcionaria era asamble\u00edsta.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.larepublica.ec\/blog\/politica\/2018\/11\/27\/exasesor-denuncia-vicuna-por-cobro-de-diezmos-en-la-asamblea\/\"><strong>Es el exasesor&nbsp;identificado como&nbsp;\u00c3\u0081ngel Sagbay quien con una declaraci\u00f3n juramentada la acusa de supuestos cobros<\/strong><\/a>. Para la segunda mandataria dicha declaraci\u00f3n es una mentira por lo que se\u00f1al\u00f3 que tomar\u00e1 las acciones legales necesarias.<\/p>\n\n\n\n<p>Seg\u00fan la vicepresidenta,&nbsp;<strong>Sagbay<\/strong>, que ha sido militante y dirigente de la&nbsp;Alianza Bolivariana Alfarista y de Alianza PAIS en su provincia, y que adem\u00e1s hasta hace poco\u009d apoyaba p\u00fablicamente la gesti\u00f3n de la Vicepresidencia y del gobierno, causa asombro que justo en estas coyunturas&nbsp;realice esta declaraci\u00f3n juramentada a partir de mentiras\u009d.<\/p>\n\n\n\n<p>El se\u00f1or Sagbay desde septiembre amenaz\u00f3 con forjar esta denuncia si no acced\u00edamos a las exigencias de cargos p\u00fablicos, particularmente de Gobernador de la provincia de Morona Santiago, de director provincial del IESS en esta provincia. Pero como no cedimos a este chantaje, a esta extorsi\u00f3n hoy se hacen p\u00fablicas estas calumnias\u009d, a\u00f1adi\u00f3&nbsp;<strong>Vicu\u00f1a<\/strong>&nbsp;en su defensa.<\/p>\n\n\n\n<p>Vicu\u00f1a ha exhibido como prueba de sus aseveraciones unos supuestos chats que no mostr\u00f3.<\/p>\n\n\n\n<p>En relaci\u00f3n directa con las acusaciones, la vicepresidenta dijo que <strong>jam\u00e1s nadie ha condicionado ni el ingreso ni la permanencia, y menos su estabilidad laboral a pagar ni un solo centavo<\/strong>.&nbsp;Todos los aportes para Alianza Bolivariana Alfarista y para Alianza PAIS, lo hemos hecho, y me incluso, en cumplimiento de nuestros deberes como militantes, en el marco de lo que establece el propio C\u00f3digo de la Democracia.&nbsp;<strong>Los aportes siempre han sido transparentes, no existen aportaciones por debajo de la mesa. A nosotros o nos financia la banca, ni los grupos de poder, ni Odebrecht<\/strong>.<\/p>\n\n\n\n<p>Vicu\u00f1a ha acusado de estar detr\u00e1s de la denuncia al excandidato a la vicepresidencia por CREO, el exlegislador Andr\u00e9s P\u00e1ez, y los corre\u00edstas\u009d. Ah\u00ed est\u00e1 el origen de la extorsi\u00f3n, mucho antes del show medi\u00e1tico de anoche. Por eso presentar\u00e9 la denuncia respectiva ante la Fiscal\u00eda\u009d. (I)<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p><strong>Fuente: <\/strong><a href=\"https:\/\/www.larepublica.ec\/blog\/politica\/2018\/11\/27\/vicuna-se-defiende-en-rueda-de-prensa-y-no-acepto-preguntas\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.larepublica.ec\/blog\/politica\/2018\/11\/27\/vicuna-se-defiende-en-rueda-de-prensa-y-no-acepto-preguntas\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vicepresidenta de la Rep\u00fablica de Ecuador,&nbsp;Mar\u00eda Alejandra Vicu\u00f1a, realiz\u00f3 una rueda de prensa (en la que no acept\u00f3 cuestionamientos) para defenderse de las acusaciones de un exasesor que la involucra en supuestos cobros indebidos cuando la funcionaria era asamble\u00edsta. Es el exasesor&nbsp;identificado como&nbsp;\u00c3\u0081ngel Sagbay quien con una declaraci\u00f3n juramentada la acusa de supuestos cobros. Para la segunda mandataria dicha declaraci\u00f3n es una mentira por lo que se\u00f1al\u00f3 que tomar\u00e1 las acciones legales necesarias. Seg\u00fan la vicepresidenta,&nbsp;Sagbay, que ha sido militante y dirigente de la&nbsp;Alianza Bolivariana Alfarista y de Alianza PAIS en su provincia, y que adem\u00e1s hasta hace poco\u009d apoyaba p\u00fablicamente la gesti\u00f3n de la Vicepresidencia y del gobierno, causa asombro que justo en estas coyunturas&nbsp;realice esta declaraci\u00f3n juramentada a partir de mentiras\u009d. El se\u00f1or Sagbay desde septiembre amenaz\u00f3 con forjar esta denuncia si no acced\u00edamos a las exigencias de cargos p\u00fablicos, particularmente de Gobernador de la provincia de Morona Santiago, de director provincial del IESS en esta provincia. Pero como no cedimos a este chantaje, a esta extorsi\u00f3n hoy se hacen p\u00fablicas estas calumnias\u009d, a\u00f1adi\u00f3&nbsp;Vicu\u00f1a&nbsp;en su defensa. Vicu\u00f1a ha exhibido como prueba de sus aseveraciones unos supuestos chats que no mostr\u00f3. En relaci\u00f3n directa con las acusaciones, la vicepresidenta dijo que jam\u00e1s nadie ha condicionado ni el ingreso ni la permanencia, y menos su estabilidad laboral a pagar ni un solo centavo.&nbsp;Todos los aportes para Alianza Bolivariana Alfarista y para Alianza PAIS, lo hemos hecho, y me incluso, en cumplimiento de nuestros deberes como militantes, en el marco de lo que establece el propio C\u00f3digo de la Democracia.&nbsp;Los aportes siempre han sido transparentes, no existen aportaciones por debajo de la mesa. A nosotros o nos financia la banca, ni los grupos de poder, ni Odebrecht. Vicu\u00f1a ha acusado de estar detr\u00e1s de la denuncia al excandidato a la vicepresidencia por CREO, el exlegislador Andr\u00e9s P\u00e1ez, y los corre\u00edstas\u009d. Ah\u00ed est\u00e1 el origen de la extorsi\u00f3n, mucho antes del show medi\u00e1tico de anoche. Por eso presentar\u00e9 la denuncia respectiva ante la Fiscal\u00eda\u009d. (I) Fuente: https:\/\/www.larepublica.ec\/blog\/politica\/2018\/11\/27\/vicuna-se-defiende-en-rueda-de-prensa-y-no-acepto-preguntas\/<\/p>\n","protected":false},"author":1,"featured_media":252138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[54,32,40,35,46],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/252137"}],"collection":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/comments?post=252137"}],"version-history":[{"count":0,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/posts\/252137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media\/252138"}],"wp:attachment":[{"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/media?parent=252137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/categories?post=252137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecuadortimes.net\/es\/wp-json\/wp\/v2\/tags?post=252137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}